{"id":5515,"date":"2022-11-10T04:32:36","date_gmt":"2022-11-10T07:32:36","guid":{"rendered":"http:\/\/brasilpelomeioambiente.com.br\/?p=5515"},"modified":"2023-10-13T12:11:00","modified_gmt":"2023-10-13T15:11:00","slug":"new-wastewater-treatment-plant-of-the-sabin-group","status":"publish","type":"post","link":"https:\/\/brasilpelomeioambiente.com.br\/en\/nova-ete-do-grupo-sabin\/","title":{"rendered":"Sabin Group's new WWTP"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5515\" class=\"elementor elementor-5515\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4b340f elementor-section-height-min-height elementor-section-items-top elementor-section-full_width menumobileclose elementor-section-height-default\" data-id=\"b4b340f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c789e14\" data-id=\"c789e14\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<nav class=\"elementor-section elementor-inner-section elementor-element elementor-element-3910369 elementor-section-content-top elementor-section-full_width elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"3910369\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<header class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2fb847a elementor-hidden-mobile\" data-id=\"2fb847a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b82fe95 elementor-widget elementor-widget-image\" data-id=\"b82fe95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/brasilpelomeioambiente.com.br\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos.png\" class=\"attachment-full size-full wp-image-1030\" alt=\"Amcham - ICC Brasil | Brasil pelo meio ambiente (BPMA))\" srcset=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos.png 1920w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos-300x169.png 300w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos-1024x576.png 1024w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos-768x432.png 768w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos-1536x864.png 1536w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos-18x10.png 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dfdde29\" data-id=\"dfdde29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e3cd03 font-book elementor-hidden-tablet elementor-hidden-mobile eael-simple-menu-hamburger-align-right eael-hamburger--tablet elementor-widget elementor-widget-eael-simple-menu\" data-id=\"7e3cd03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-simple-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n                        @media screen and (max-width: 1024px) {\n                            .eael-hamburger--tablet {\n                                .eael-simple-menu-horizontal,\n                                .eael-simple-menu-vertical {\n                                    display: none;\n                                }\n                            }\n                            .eael-hamburger--tablet {\n                                .eael-simple-menu-container .eael-simple-menu-toggle {\n                                    display: block;\n                                }\n                            }\n                        }\n                        .eael-simple-menu-container.eael-simple-menu--loading > ul {\n                            display: -webkit-box !important;\n                            display: -ms-flexbox !important;\n                            display: flex !important;\n                            list-style: none !important;\n                        }\n                        .eael-simple-menu-container.eael-simple-menu--loading li ul {\n                            visibility: hidden !important;\n                            opacity: 0 !important;\n                        }\n                    <\/style>            <div data-hamburger-icon=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-bars&quot;&gt;&lt;\/i&gt;\" data-indicator-icon=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" data-dropdown-indicator-icon=\"&lt;i class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" class=\"eael-simple-menu-container eael-simple-menu--loading eael-simple-menu-align-center eael-simple-menu-dropdown-align-left preset-1\" data-hamburger-breakpoints=\"{&quot;mobile&quot;:&quot;Mobile Portrait (&gt; 767px)&quot;,&quot;tablet&quot;:&quot;Tablet Portrait (&gt; 1024px)&quot;,&quot;desktop&quot;:&quot;Desktop (&gt; 2400px)&quot;,&quot;none&quot;:&quot;None&quot;}\" data-hamburger-device=\"tablet\">\n                <ul id=\"menu-menu\" class=\"eael-simple-menu eael-simple-menu-dropdown-animate-to-top eael-simple-menu-indicator eael-hamburger-center eael-simple-menu-horizontal\"><li id=\"menu-item-56\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-56\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/sobre\/\">O QUE \u00c9<\/a><\/li>\n<li id=\"menu-item-55\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-55\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/como-participar\/\">COMO PARTICIPAR<\/a><\/li>\n<li id=\"menu-item-93\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-93\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/projetos\/\">PROJETOS<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-8580\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8580\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/categoria-2024\/\">CATEGORIA<\/a><\/li>\n\t<li id=\"menu-item-8577\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8577\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/setor-2024\/\">SETOR<\/a><\/li>\n\t<li id=\"menu-item-8578\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8578\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/regiao-2024\/\">REGI\u00c3O<\/a><\/li>\n\t<li id=\"menu-item-8579\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8579\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/ods-2024\/\">ODS<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-92\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-92\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/fale-conosco\/\">FALE CONOSCO<\/a><\/li>\n<li id=\"menu-item-5592\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5592\"><a href=\"#\">Idioma<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-5548\" class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-5548\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/posts\/5515#TRPLINKPROCESSED\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/pt_BR.png\" width=\"18\" height=\"12\" alt=\"pt_BR\" title=\"Portugu\u00eas do Brasil\"><span class=\"trp-ls-language-name\">PT<\/span><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>                <button class=\"eael-simple-menu-toggle\">\n                    <span class=\"sr-only \">Hamburger Toggle Menu<\/span>\n                    <i aria-hidden=\"true\" class=\"fas fa-bars\"><\/i>                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-df5cc4f\" data-id=\"df5cc4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a89f801 hfe-search-layout-icon elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-hfe-search-button\" data-id=\"a89f801\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;input_icon_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:368,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;none&quot;,&quot;toggle_icon_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;input_icon_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;input_icon_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_icon_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_icon_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"hfe-search-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"hfe-search-button-wrapper\" role=\"search\" action=\"https:\/\/brasilpelomeioambiente.com.br\/\" method=\"get\">\n\n\t\t\t\t\t\t<div class = \"hfe-search-icon-toggle\">\n\t\t\t\t<input placeholder=\"\" class=\"hfe-search-form__input\" type=\"search\" name=\"s\" title=\"Search\" value=\"\">\n\t\t\t\t<i class=\"fas fa-search\" aria-hidden=\"true\"><\/i>\n\t\t\t<\/div>\n\t\t\t\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t<header class=\"elementor-section elementor-inner-section elementor-element elementor-element-3234648 elementor-section-content-middle elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"3234648\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<header class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e1b6caf\" data-id=\"e1b6caf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-691c077 elementor-widget elementor-widget-image\" data-id=\"691c077\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/brasilpelomeioambiente.com.br\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/elementor\/thumbs\/AMCHAM-ICC-2-qw84my8i6tp99e0frn3mx4ejmcvhnimzm3jh7jg4tu.webp\" title=\"AMCHAM-ICC-2\" alt=\"AMCHAM-ICC-2\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7a25d9e\" data-id=\"7a25d9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-200db86 elementor-widget elementor-widget-image\" data-id=\"200db86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/elementor\/thumbs\/BpMA-1-qw84my8i6tp99e0frn3mx4ejmcvhnimzm3jh7jg3xc.webp\" title=\"BpMA-1\" alt=\"BpMA-1\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d715231\" data-id=\"d715231\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6809f53 elementor-widget elementor-widget-html\" data-id=\"6809f53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"#\"  onclick=\"show()\" ><i  style=\"color: #fff; font-size: 70px; padding: 0 0.2em 0 0; float: right;\" aria-hidden=\"true\" class=\"fas fa-bars\"><\/i><\/a>\n<style>\n.menumobile {\n    display: none;\n}\n<\/style>\n\n<script>\nsetTimeout(() => {\n  document.getElementsByClassName('menumobile')[0].style.display = \"none\";\n}, 1000)\n\nfunction show(){\n    if(document.getElementsByClassName('menumobile')[0].style.display == \"none\")\n    {\n    document.getElementsByClassName('menumobile')[0].style.display = 'block';\n    document.getElementsByClassName('menumobileclose')[0].style.display = 'none';\n    }else{\n        document.getElementsByClassName('menumobileclose')[0].style.display = 'block';\n        document.getElementsByClassName('menumobile')[0].style.display = 'none';\n    }\n}\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-086de16 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"086de16\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cd647d5 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"cd647d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cb96a01\" data-id=\"cb96a01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45b68e8 elementor-hidden-tablet elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"45b68e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fcf250e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fcf250e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f8aade8\" data-id=\"f8aade8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d584efa titulo-p elementor-widget elementor-widget-heading\" data-id=\"d584efa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Nova ETE do Grupo Sabin<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81dee55 titulo-e elementor-widget elementor-widget-heading\" data-id=\"81dee55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Grupo Sabin<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2acf216 elementor-section-full_width menumobile elementor-section-height-default elementor-section-height-default\" data-id=\"2acf216\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60a244a\" data-id=\"60a244a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c73f071 elementor-section-content-middle elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"c73f071\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<header class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3142fb2\" data-id=\"3142fb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39e1b59 elementor-widget elementor-widget-image\" data-id=\"39e1b59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/elementor\/thumbs\/AMCHAM-ICC-1-qw84my8i6tp99e0frn3mx4ejmcvhnimzm3jh7jg4tu.png\" title=\"AMCHAM + ICC (1)\" alt=\"AMCHAM + ICC (1)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-74151ef\" data-id=\"74151ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0743a89 elementor-widget elementor-widget-image\" data-id=\"0743a89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/elementor\/thumbs\/BpMA-2-qw84my8i6tp99e0frn3mx4ejmcvhnimzm3jh7jg3xc.png\" title=\"BpMA (2)\" alt=\"BpMA (2)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4bd07a7\" data-id=\"4bd07a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0879448 elementor-widget elementor-widget-html\" data-id=\"0879448\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"#\"  onclick=\"show()\" ><i  style=\"color: #001A3F; font-size: 70px; padding: 0 0.2em 0 0; float: right;\" aria-hidden=\"true\" class=\"fas fa-times\"><\/i><\/a>\n<style>\n.menumobile {\n    display: none;\n}\n<\/style>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-95a939a elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"95a939a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bde9784\" data-id=\"bde9784\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acd66f0 elementor-hidden-desktop elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"acd66f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02a25c2 eael_simple_menu_hamburger_disable_selected_menu_hide elementor-widget-mobile__width-inherit eael-simple-menu-hamburger-align-right eael-hamburger--tablet elementor-widget elementor-widget-eael-simple-menu\" data-id=\"02a25c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-simple-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n                        @media screen and (max-width: 1024px) {\n                            .eael-hamburger--tablet {\n                                .eael-simple-menu-horizontal,\n                                .eael-simple-menu-vertical {\n                                    display: none;\n                                }\n                            }\n                            .eael-hamburger--tablet {\n                                .eael-simple-menu-container .eael-simple-menu-toggle {\n                                    display: block;\n                                }\n                            }\n                        }\n                        .eael-simple-menu-container.eael-simple-menu--loading > ul {\n                            display: -webkit-box !important;\n                            display: -ms-flexbox !important;\n                            display: flex !important;\n                            list-style: none !important;\n                        }\n                        .eael-simple-menu-container.eael-simple-menu--loading li ul {\n                            visibility: hidden !important;\n                            opacity: 0 !important;\n                        }\n                    <\/style>            <div data-hamburger-icon=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-bars&quot;&gt;&lt;\/i&gt;\" data-indicator-icon=\"\" data-dropdown-indicator-icon=\"&lt;i class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" class=\"eael-simple-menu-container eael-simple-menu--loading eael-simple-menu-align-left eael-simple-menu-dropdown-align-left preset-1\" data-hamburger-breakpoints=\"{&quot;mobile&quot;:&quot;Mobile Portrait (&gt; 767px)&quot;,&quot;tablet&quot;:&quot;Tablet Portrait (&gt; 1024px)&quot;,&quot;desktop&quot;:&quot;Desktop (&gt; 2400px)&quot;,&quot;none&quot;:&quot;None&quot;}\" data-hamburger-device=\"tablet\">\n                <ul id=\"menu-menu-1\" class=\"eael-simple-menu eael-simple-menu-dropdown-animate-to-top eael-simple-menu-indicator eael-simple-menu-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-56\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/sobre\/\">O QUE \u00c9<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-55\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/como-participar\/\">COMO PARTICIPAR<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-93\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/projetos\/\">PROJETOS<\/a>\n<ul class=\"sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8580\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/categoria-2024\/\">CATEGORIA<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8577\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/setor-2024\/\">SETOR<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8578\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/regiao-2024\/\">REGI\u00c3O<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8579\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/ods-2024\/\">ODS<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-92\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/fale-conosco\/\">FALE CONOSCO<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5592\"><a href=\"#\">Idioma<\/a>\n<ul class=\"sub-menu\">\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-5548\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/posts\/5515#TRPLINKPROCESSED\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/pt_BR.png\" width=\"18\" height=\"12\" alt=\"pt_BR\" title=\"Portugu\u00eas do Brasil\"><span class=\"trp-ls-language-name\">PT<\/span><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>                <button class=\"eael-simple-menu-toggle\">\n                    <span class=\"sr-only \">Hamburger Toggle Menu<\/span>\n                    <i aria-hidden=\"true\" class=\"fas fa-bars\"><\/i>                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-641c801 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"641c801\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e77eddd social-share\" data-id=\"e77eddd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-463e815 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"463e815\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-0e0f242\" data-id=\"0e0f242\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2651a8d elementor-widget elementor-widget-heading\" data-id=\"2651a8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">O QUE \u00c9<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c64116 elementor-widget elementor-widget-text-editor\" data-id=\"9c64116\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Em 2021, foi constru\u00edda e inaugurada uma Esta\u00e7\u00e3o de Tratamento de Efluentes (ETE) para o N\u00facleo T\u00e9cnico Operacional (NTO) central, onde s\u00e3o processados o maior volume de exames de an\u00e1lises cl\u00ednicas do Grupo, e com isso, a maior unidade produtora de efluentes do Grupo.<\/p><p>\u00a0<\/p><p>A instala\u00e7\u00e3o totalmente automatizada passou a garantir, a partir de outubro de 2021, o reuso da \u00e1gua na sede administrativa do Grupo, em Bras\u00edlia, e reduzindo, assim, o impacto ambiental das atividades da empresa. A ETE inaugurada permitiu o reaproveitamento h\u00eddrico e o tratamento dos efluentes gerados pela \u00e1rea t\u00e9cnica e desde que entrou em opera\u00e7\u00e3o, a esta\u00e7\u00e3o melhorou os indicadores ambientais do Grupo Sabin.<\/p><p>\u00a0<\/p><p>Com o novo equipamento, os recursos h\u00eddricos utilizados no processamento dos exames de an\u00e1lises cl\u00ednicas, das amostras recebidas no NTO de Bras\u00edlia, passaram a ser tratados e direcionados para a rega de jardins e descargas sanit\u00e1rias da sede administrativa, em Bras\u00edlia.<\/p><p>\u00a0<\/p><p>O projeto contribui para o fortalecimento do ODS 6 e colabora para aumentar a disponibilidade de \u00e1gua nos reservat\u00f3rios que abastecem a cidade toda a capital federal.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6e164f elementor-widget elementor-widget-heading\" data-id=\"c6e164f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Resultados e Objetivos<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc2a050 elementor-widget elementor-widget-text-editor\" data-id=\"dc2a050\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Resultados alcan\u00e7ados:<\/p><p><br \/>100% da \u00e1gua utilizada no processo produtivo \u00e9 reutilizada;<br \/>Redu\u00e7\u00e3o de 22,8% no consumo total de \u00e1gua desde a implanta\u00e7\u00e3o da ETE, em compara\u00e7\u00e3o com o per\u00edodo anterior;<br \/>Redu\u00e7\u00e3o de 26,5 % no consumo de \u00e1gua\/por exame (uso relativo a setembro de 2022 em rela\u00e7\u00e3o a setembro de 2021);<br \/>Total de efluentes tratados e reutilizados na sede administrativa da empresa, em Brasilia: 3.128,000 m3\/ano<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<aside class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1fe6d80\" data-id=\"1fe6d80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-45b9b70 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45b9b70\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9a43058 project-side-item project-sectors\" data-id=\"9a43058\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0f6247 elementor-widget elementor-widget-heading\" data-id=\"e0f6247\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">regi\u00e3o<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9f341a elementor-widget elementor-widget-heading\" data-id=\"a9f341a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nacional<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ebf8914 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ebf8914\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b180d9e project-side-item project-investments\" data-id=\"b180d9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ddfea2 elementor-widget elementor-widget-heading\" data-id=\"4ddfea2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">n\u00fameros<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6adaa3 elementor-widget elementor-widget-premium-counter\" data-id=\"e6adaa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"premium-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"premium-counter premium-counter-area top\" data-duration=\"3000\" data-from-value=\"0\" data-to-value=\"3.1\" data-delimiter=\".\" data-rounding=\"1\">\n\t\t\t\n\t\t<div class=\"premium-counter-icon\">\n\n\t\t\t<span class=\"icon\" data-animation=\"\">\n\n\t\t\t\t\t\t\t\t\t<i class=\"premium-svg-nodraw premium-drawable-icon fas fa-trash-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\n\t\t\t<\/span>\n\t\t<\/div>\n\n\t\t\n\t\t<div class=\"premium-init-wrapper column\">\n\n\t\t\t<div class=\"premium-counter-value-wrap\">\n\t\t\t\t\n\t\t\t\t<span class=\"premium-counter-init\" id=\"counter-e6adaa3\">0<\/span>\n\n\t\t\t\t\t\t\t\t\t<span id=\"suffix\" class=\"counter-su-pre\">mil m\u00b3\/ano<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-counter-title\">\n\t\t\t\t\t<p class=\"premium-counter-title-val\">\n\t\t\t\t\t\t de efluentes que deixaram de ser destinados ao meio ambiente\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"premium-counter-desc\"> Por meio  de tratamento e reutiliza\u00e7\u00e3o<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aa09ee0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa09ee0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-53bf903 project-side-item project-sectors\" data-id=\"53bf903\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12a6c5d elementor-widget elementor-widget-heading\" data-id=\"12a6c5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">setor<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0698408 elementor-widget elementor-widget-heading\" data-id=\"0698408\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Com\u00e9rcio e Servi\u00e7os<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2261646 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2261646\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bc05213 project-side-item project-categories\" data-id=\"bc05213\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3b5c2f elementor-widget elementor-widget-heading\" data-id=\"e3b5c2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">CATEGORIA<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1aaa1d project-categories-list elementor-widget elementor-widget-text-editor\" data-id=\"b1aaa1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tManejo de Res\u00edduos e Cadeias Log\u00edsticas\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/aside>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sabin Group<\/p>","protected":false},"author":5,"featured_media":5483,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[161,53,43,10,52,51,76,54,55],"tags":[164,156],"class_list":["post-5515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-161","category-centro-oeste","category-comercio-e-servico","category-residuos_cadeias_logisticas","category-nordeste","category-norte","category-s","category-sudeste","category-sul","tag-164","tag-grupo-sabin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nova ETE do Grupo Sabin - Brasil Pelo Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/new-wastewater-treatment-plant-of-the-sabin-group\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nova ETE do Grupo Sabin - Brasil Pelo Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Grupo Sabin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brasilpelomeioambiente.com.br\/en\/new-wastewater-treatment-plant-of-the-sabin-group\/\" \/>\n<meta property=\"og:site_name\" content=\"Brasil Pelo Meio Ambiente\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amchambrasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-10T07:32:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-13T15:11:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/11\/contaminantes-da-agua-quad.png\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"275\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Kaike Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amchambr\" \/>\n<meta name=\"twitter:site\" content=\"@amchambr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kaike Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/nova-ete-do-grupo-sabin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/nova-ete-do-grupo-sabin\\\/\"},\"author\":{\"name\":\"Kaike Silveira\",\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#\\\/schema\\\/person\\\/9d0a98e02ce7aaaad190174d8c02d8ff\"},\"headline\":\"Nova ETE do Grupo Sabin\",\"datePublished\":\"2022-11-10T07:32:36+00:00\",\"dateModified\":\"2023-10-13T15:11:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/nova-ete-do-grupo-sabin\\\/\"},\"wordCount\":336,\"publisher\":{\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/nova-ete-do-grupo-sabin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/contaminantes-da-agua-quad.png\",\"keywords\":[\"2022\",\"Grupo Sabin\"],\"articleSection\":[\"2022\",\"Centro-Oeste\",\"Com\u00e9rcio e Servi\u00e7o\",\"Manejo de Res\u00edduos e Cadeias Log\u00edsticas\",\"Nordeste\",\"Norte\",\"S\",\"Sudeste\",\"Sul\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/nova-ete-do-grupo-sabin\\\/\",\"url\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/nova-ete-do-grupo-sabin\\\/\",\"name\":\"Nova ETE do Grupo Sabin - Brasil Pelo Meio Ambiente\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/nova-ete-do-grupo-sabin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/nova-ete-do-grupo-sabin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/contaminantes-da-agua-quad.png\",\"datePublished\":\"2022-11-10T07:32:36+00:00\",\"dateModified\":\"2023-10-13T15:11:00+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/nova-ete-do-grupo-sabin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/nova-ete-do-grupo-sabin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/contaminantes-da-agua-quad.png\",\"contentUrl\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/contaminantes-da-agua-quad.png\",\"width\":275,\"height\":275},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#website\",\"url\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/\",\"name\":\"Brasil Pelo Meio Ambiente\",\"description\":\"O projeto Brasil Pelo Meio Ambiente surgiu da necessidade de compartilhar as melhores pr\u00e1ticas empresariais brasileiras sobre os temas de preserva\u00e7\u00e3o ambiental e sustentabilidade\",\"publisher\":{\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#organization\"},\"alternateName\":\"BPMA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#organization\",\"name\":\"Brasil Pelo Meio Ambiente\",\"url\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/BpMA-Amcham-ICC_logotipos.png\",\"contentUrl\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/BpMA-Amcham-ICC_logotipos.png\",\"width\":1920,\"height\":1080,\"caption\":\"Brasil Pelo Meio Ambiente\"},\"image\":{\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amchambrasil\",\"https:\\\/\\\/x.com\\\/amchambr\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#\\\/schema\\\/person\\\/9d0a98e02ce7aaaad190174d8c02d8ff\",\"name\":\"Kaike Silveira\",\"url\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/en\\\/author\\\/kaike-silveira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New Wastewater Treatment Plant of the Sabin Group - Brazil for the Environment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brasilpelomeioambiente.com.br\/en\/new-wastewater-treatment-plant-of-the-sabin-group\/","og_locale":"en_US","og_type":"article","og_title":"Nova ETE do Grupo Sabin - Brasil Pelo Meio Ambiente","og_description":"Grupo Sabin","og_url":"https:\/\/brasilpelomeioambiente.com.br\/en\/new-wastewater-treatment-plant-of-the-sabin-group\/","og_site_name":"Brasil Pelo Meio Ambiente","article_publisher":"https:\/\/www.facebook.com\/amchambrasil","article_published_time":"2022-11-10T07:32:36+00:00","article_modified_time":"2023-10-13T15:11:00+00:00","og_image":[{"width":275,"height":275,"url":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/11\/contaminantes-da-agua-quad.png","type":"image\/png"}],"author":"Kaike Silveira","twitter_card":"summary_large_image","twitter_creator":"@amchambr","twitter_site":"@amchambr","twitter_misc":{"Written by":"Kaike Silveira","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/brasilpelomeioambiente.com.br\/nova-ete-do-grupo-sabin\/#article","isPartOf":{"@id":"https:\/\/brasilpelomeioambiente.com.br\/nova-ete-do-grupo-sabin\/"},"author":{"name":"Kaike Silveira","@id":"http:\/\/brasilpelomeioambiente.com.br\/#\/schema\/person\/9d0a98e02ce7aaaad190174d8c02d8ff"},"headline":"Nova ETE do Grupo Sabin","datePublished":"2022-11-10T07:32:36+00:00","dateModified":"2023-10-13T15:11:00+00:00","mainEntityOfPage":{"@id":"https:\/\/brasilpelomeioambiente.com.br\/nova-ete-do-grupo-sabin\/"},"wordCount":336,"publisher":{"@id":"http:\/\/brasilpelomeioambiente.com.br\/#organization"},"image":{"@id":"https:\/\/brasilpelomeioambiente.com.br\/nova-ete-do-grupo-sabin\/#primaryimage"},"thumbnailUrl":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/11\/contaminantes-da-agua-quad.png","keywords":["2022","Grupo Sabin"],"articleSection":["2022","Centro-Oeste","Com\u00e9rcio e Servi\u00e7o","Manejo de Res\u00edduos e Cadeias Log\u00edsticas","Nordeste","Norte","S","Sudeste","Sul"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/brasilpelomeioambiente.com.br\/nova-ete-do-grupo-sabin\/","url":"https:\/\/brasilpelomeioambiente.com.br\/nova-ete-do-grupo-sabin\/","name":"New Wastewater Treatment Plant of the Sabin Group - Brazil for the Environment","isPartOf":{"@id":"http:\/\/brasilpelomeioambiente.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brasilpelomeioambiente.com.br\/nova-ete-do-grupo-sabin\/#primaryimage"},"image":{"@id":"https:\/\/brasilpelomeioambiente.com.br\/nova-ete-do-grupo-sabin\/#primaryimage"},"thumbnailUrl":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/11\/contaminantes-da-agua-quad.png","datePublished":"2022-11-10T07:32:36+00:00","dateModified":"2023-10-13T15:11:00+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brasilpelomeioambiente.com.br\/nova-ete-do-grupo-sabin\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/brasilpelomeioambiente.com.br\/nova-ete-do-grupo-sabin\/#primaryimage","url":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/11\/contaminantes-da-agua-quad.png","contentUrl":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/11\/contaminantes-da-agua-quad.png","width":275,"height":275},{"@type":"WebSite","@id":"http:\/\/brasilpelomeioambiente.com.br\/#website","url":"http:\/\/brasilpelomeioambiente.com.br\/","name":"Brazil for the Environment","description":"The Brazil for the Environment project arose from the need to share Brazil's best business practices on the issues of environmental preservation and sustainability","publisher":{"@id":"http:\/\/brasilpelomeioambiente.com.br\/#organization"},"alternateName":"BPMA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/brasilpelomeioambiente.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/brasilpelomeioambiente.com.br\/#organization","name":"Brazil for the Environment","url":"http:\/\/brasilpelomeioambiente.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/brasilpelomeioambiente.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos.png","contentUrl":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos.png","width":1920,"height":1080,"caption":"Brasil Pelo Meio Ambiente"},"image":{"@id":"http:\/\/brasilpelomeioambiente.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amchambrasil","https:\/\/x.com\/amchambr"]},{"@type":"Person","@id":"http:\/\/brasilpelomeioambiente.com.br\/#\/schema\/person\/9d0a98e02ce7aaaad190174d8c02d8ff","name":"Kaike Silveira","url":"https:\/\/brasilpelomeioambiente.com.br\/en\/author\/kaike-silveira\/"}]}},"_links":{"self":[{"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/posts\/5515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/comments?post=5515"}],"version-history":[{"count":0,"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/posts\/5515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/media\/5483"}],"wp:attachment":[{"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/media?parent=5515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/categories?post=5515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/tags?post=5515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}