{"id":5525,"date":"2022-11-10T07:01:02","date_gmt":"2022-11-10T10:01:02","guid":{"rendered":"http:\/\/brasilpelomeioambiente.com.br\/?p=5525"},"modified":"2023-10-11T14:31:41","modified_gmt":"2023-10-11T17:31:41","slug":"honey-green-project","status":"publish","type":"post","link":"https:\/\/brasilpelomeioambiente.com.br\/en\/projeto-verde-mel\/","title":{"rendered":"Green Honey project"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5525\" class=\"elementor elementor-5525\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4b340f elementor-section-height-min-height elementor-section-items-top elementor-section-full_width menumobileclose elementor-section-height-default\" data-id=\"b4b340f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c789e14\" data-id=\"c789e14\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<nav class=\"elementor-section elementor-inner-section elementor-element elementor-element-3910369 elementor-section-content-top elementor-section-full_width elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"3910369\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<header class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2fb847a elementor-hidden-mobile\" data-id=\"2fb847a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b82fe95 elementor-widget elementor-widget-image\" data-id=\"b82fe95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/brasilpelomeioambiente.com.br\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos.png\" class=\"attachment-full size-full wp-image-1030\" alt=\"Amcham - ICC Brasil | Brasil pelo meio ambiente (BPMA))\" srcset=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos.png 1920w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos-300x169.png 300w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos-1024x576.png 1024w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos-768x432.png 768w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos-1536x864.png 1536w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos_brancos-18x10.png 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dfdde29\" data-id=\"dfdde29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e3cd03 font-book elementor-hidden-tablet elementor-hidden-mobile eael-simple-menu-hamburger-align-right eael-hamburger--tablet elementor-widget elementor-widget-eael-simple-menu\" data-id=\"7e3cd03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-simple-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n                        @media screen and (max-width: 1024px) {\n                            .eael-hamburger--tablet {\n                                .eael-simple-menu-horizontal,\n                                .eael-simple-menu-vertical {\n                                    display: none;\n                                }\n                            }\n                            .eael-hamburger--tablet {\n                                .eael-simple-menu-container .eael-simple-menu-toggle {\n                                    display: block;\n                                }\n                            }\n                        }\n                        .eael-simple-menu-container.eael-simple-menu--loading > ul {\n                            display: -webkit-box !important;\n                            display: -ms-flexbox !important;\n                            display: flex !important;\n                            list-style: none !important;\n                        }\n                        .eael-simple-menu-container.eael-simple-menu--loading li ul {\n                            visibility: hidden !important;\n                            opacity: 0 !important;\n                        }\n                    <\/style>            <div data-hamburger-icon=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-bars&quot;&gt;&lt;\/i&gt;\" data-indicator-icon=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" data-dropdown-indicator-icon=\"&lt;i class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" class=\"eael-simple-menu-container eael-simple-menu--loading eael-simple-menu-align-center eael-simple-menu-dropdown-align-left preset-1\" data-hamburger-breakpoints=\"{&quot;mobile&quot;:&quot;Mobile Portrait (&gt; 767px)&quot;,&quot;tablet&quot;:&quot;Tablet Portrait (&gt; 1024px)&quot;,&quot;desktop&quot;:&quot;Desktop (&gt; 2400px)&quot;,&quot;none&quot;:&quot;None&quot;}\" data-hamburger-device=\"tablet\">\n                <ul id=\"menu-menu\" class=\"eael-simple-menu eael-simple-menu-dropdown-animate-to-top eael-simple-menu-indicator eael-hamburger-center eael-simple-menu-horizontal\"><li id=\"menu-item-56\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-56\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/sobre\/\">O QUE \u00c9<\/a><\/li>\n<li id=\"menu-item-55\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-55\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/como-participar\/\">COMO PARTICIPAR<\/a><\/li>\n<li id=\"menu-item-93\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-93\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/projetos\/\">PROJETOS<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-8580\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8580\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/categoria-2024\/\">CATEGORIA<\/a><\/li>\n\t<li id=\"menu-item-8577\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8577\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/setor-2024\/\">SETOR<\/a><\/li>\n\t<li id=\"menu-item-8578\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8578\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/regiao-2024\/\">REGI\u00c3O<\/a><\/li>\n\t<li id=\"menu-item-8579\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8579\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/ods-2024\/\">ODS<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-92\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-92\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/fale-conosco\/\">FALE CONOSCO<\/a><\/li>\n<li id=\"menu-item-5592\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5592\"><a href=\"#\">Idioma<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-5548\" class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-5548\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/posts\/5525#TRPLINKPROCESSED\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/pt_BR.png\" width=\"18\" height=\"12\" alt=\"pt_BR\" title=\"Portugu\u00eas do Brasil\"><span class=\"trp-ls-language-name\">PT<\/span><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>                <button class=\"eael-simple-menu-toggle\">\n                    <span class=\"sr-only \">Hamburger Toggle Menu<\/span>\n                    <i aria-hidden=\"true\" class=\"fas fa-bars\"><\/i>                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-df5cc4f\" data-id=\"df5cc4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a89f801 hfe-search-layout-icon elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-hfe-search-button\" data-id=\"a89f801\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;input_icon_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:368,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;none&quot;,&quot;toggle_icon_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;input_icon_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;input_icon_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_icon_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_icon_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"hfe-search-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"hfe-search-button-wrapper\" role=\"search\" action=\"https:\/\/brasilpelomeioambiente.com.br\/\" method=\"get\">\n\n\t\t\t\t\t\t<div class = \"hfe-search-icon-toggle\">\n\t\t\t\t<input placeholder=\"\" class=\"hfe-search-form__input\" type=\"search\" name=\"s\" title=\"Search\" value=\"\">\n\t\t\t\t<i class=\"fas fa-search\" aria-hidden=\"true\"><\/i>\n\t\t\t<\/div>\n\t\t\t\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t<header class=\"elementor-section elementor-inner-section elementor-element elementor-element-3234648 elementor-section-content-middle elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"3234648\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<header class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e1b6caf\" data-id=\"e1b6caf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-691c077 elementor-widget elementor-widget-image\" data-id=\"691c077\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/brasilpelomeioambiente.com.br\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/elementor\/thumbs\/AMCHAM-ICC-2-qw84my8i6tp99e0frn3mx4ejmcvhnimzm3jh7jg4tu.webp\" title=\"AMCHAM-ICC-2\" alt=\"AMCHAM-ICC-2\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7a25d9e\" data-id=\"7a25d9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-200db86 elementor-widget elementor-widget-image\" data-id=\"200db86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/elementor\/thumbs\/BpMA-1-qw84my8i6tp99e0frn3mx4ejmcvhnimzm3jh7jg3xc.webp\" title=\"BpMA-1\" alt=\"BpMA-1\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d715231\" data-id=\"d715231\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6809f53 elementor-widget elementor-widget-html\" data-id=\"6809f53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"#\"  onclick=\"show()\" ><i  style=\"color: #fff; font-size: 70px; padding: 0 0.2em 0 0; float: right;\" aria-hidden=\"true\" class=\"fas fa-bars\"><\/i><\/a>\n<style>\n.menumobile {\n    display: none;\n}\n<\/style>\n\n<script>\nsetTimeout(() => {\n  document.getElementsByClassName('menumobile')[0].style.display = \"none\";\n}, 1000)\n\nfunction show(){\n    if(document.getElementsByClassName('menumobile')[0].style.display == \"none\")\n    {\n    document.getElementsByClassName('menumobile')[0].style.display = 'block';\n    document.getElementsByClassName('menumobileclose')[0].style.display = 'none';\n    }else{\n        document.getElementsByClassName('menumobileclose')[0].style.display = 'block';\n        document.getElementsByClassName('menumobile')[0].style.display = 'none';\n    }\n}\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-086de16 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"086de16\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cd647d5 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"cd647d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cb96a01\" data-id=\"cb96a01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45b68e8 elementor-hidden-tablet elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"45b68e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fcf250e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fcf250e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f8aade8\" data-id=\"f8aade8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d584efa titulo-p elementor-widget elementor-widget-heading\" data-id=\"d584efa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Projeto Verde Mel<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81dee55 titulo-e elementor-widget elementor-widget-heading\" data-id=\"81dee55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sylvamo do Brasil<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2acf216 elementor-section-full_width menumobile elementor-section-height-default elementor-section-height-default\" data-id=\"2acf216\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60a244a\" data-id=\"60a244a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c73f071 elementor-section-content-middle elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"c73f071\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<header class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3142fb2\" data-id=\"3142fb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39e1b59 elementor-widget elementor-widget-image\" data-id=\"39e1b59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/elementor\/thumbs\/AMCHAM-ICC-1-qw84my8i6tp99e0frn3mx4ejmcvhnimzm3jh7jg4tu.png\" title=\"AMCHAM + ICC (1)\" alt=\"AMCHAM + ICC (1)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-74151ef\" data-id=\"74151ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0743a89 elementor-widget elementor-widget-image\" data-id=\"0743a89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/elementor\/thumbs\/BpMA-2-qw84my8i6tp99e0frn3mx4ejmcvhnimzm3jh7jg3xc.png\" title=\"BpMA (2)\" alt=\"BpMA (2)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4bd07a7\" data-id=\"4bd07a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0879448 elementor-widget elementor-widget-html\" data-id=\"0879448\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"#\"  onclick=\"show()\" ><i  style=\"color: #001A3F; font-size: 70px; padding: 0 0.2em 0 0; float: right;\" aria-hidden=\"true\" class=\"fas fa-times\"><\/i><\/a>\n<style>\n.menumobile {\n    display: none;\n}\n<\/style>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-95a939a elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"95a939a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bde9784\" data-id=\"bde9784\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acd66f0 elementor-hidden-desktop elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"acd66f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02a25c2 eael_simple_menu_hamburger_disable_selected_menu_hide elementor-widget-mobile__width-inherit eael-simple-menu-hamburger-align-right eael-hamburger--tablet elementor-widget elementor-widget-eael-simple-menu\" data-id=\"02a25c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-simple-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n                        @media screen and (max-width: 1024px) {\n                            .eael-hamburger--tablet {\n                                .eael-simple-menu-horizontal,\n                                .eael-simple-menu-vertical {\n                                    display: none;\n                                }\n                            }\n                            .eael-hamburger--tablet {\n                                .eael-simple-menu-container .eael-simple-menu-toggle {\n                                    display: block;\n                                }\n                            }\n                        }\n                        .eael-simple-menu-container.eael-simple-menu--loading > ul {\n                            display: -webkit-box !important;\n                            display: -ms-flexbox !important;\n                            display: flex !important;\n                            list-style: none !important;\n                        }\n                        .eael-simple-menu-container.eael-simple-menu--loading li ul {\n                            visibility: hidden !important;\n                            opacity: 0 !important;\n                        }\n                    <\/style>            <div data-hamburger-icon=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-bars&quot;&gt;&lt;\/i&gt;\" data-indicator-icon=\"\" data-dropdown-indicator-icon=\"&lt;i class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" class=\"eael-simple-menu-container eael-simple-menu--loading eael-simple-menu-align-left eael-simple-menu-dropdown-align-left preset-1\" data-hamburger-breakpoints=\"{&quot;mobile&quot;:&quot;Mobile Portrait (&gt; 767px)&quot;,&quot;tablet&quot;:&quot;Tablet Portrait (&gt; 1024px)&quot;,&quot;desktop&quot;:&quot;Desktop (&gt; 2400px)&quot;,&quot;none&quot;:&quot;None&quot;}\" data-hamburger-device=\"tablet\">\n                <ul id=\"menu-menu-1\" class=\"eael-simple-menu eael-simple-menu-dropdown-animate-to-top eael-simple-menu-indicator eael-simple-menu-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-56\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/sobre\/\">O QUE \u00c9<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-55\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/como-participar\/\">COMO PARTICIPAR<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-93\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/projetos\/\">PROJETOS<\/a>\n<ul class=\"sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8580\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/categoria-2024\/\">CATEGORIA<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8577\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/setor-2024\/\">SETOR<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8578\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/regiao-2024\/\">REGI\u00c3O<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8579\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/ods-2024\/\">ODS<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-92\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/fale-conosco\/\">FALE CONOSCO<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-5592\"><a href=\"#\">Idioma<\/a>\n<ul class=\"sub-menu\">\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-5548\"><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/posts\/5525#TRPLINKPROCESSED\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/pt_BR.png\" width=\"18\" height=\"12\" alt=\"pt_BR\" title=\"Portugu\u00eas do Brasil\"><span class=\"trp-ls-language-name\">PT<\/span><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>                <button class=\"eael-simple-menu-toggle\">\n                    <span class=\"sr-only \">Hamburger Toggle Menu<\/span>\n                    <i aria-hidden=\"true\" class=\"fas fa-bars\"><\/i>                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-641c801 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"641c801\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e77eddd social-share\" data-id=\"e77eddd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-463e815 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"463e815\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-0e0f242\" data-id=\"0e0f242\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2651a8d elementor-widget elementor-widget-heading\" data-id=\"2651a8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">O QUE \u00c9<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c64116 elementor-widget elementor-widget-text-editor\" data-id=\"9c64116\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Comprometida com a conserva\u00e7\u00e3o de florestas saud\u00e1veis e abundantes e tamb\u00e9m com o desenvolvimento das comunidades das quais faz parte, a Sylvamo, firmou parceria com o Instituto ATA, organiza\u00e7\u00e3o n\u00e3o governamental que tem como principal miss\u00e3o valorizar os ingredientes, produtores e territ\u00f3rios produtivos do Brasil. A partir da uni\u00e3o de prop\u00f3sitos destas organiza\u00e7\u00f5es, nasceu, em 2020, o Projeto Verde Mel. A iniciativa tem o objetivo de incentivar o manejo respons\u00e1vel de abelhas nativas sem ferr\u00e3o, valorizar a meliponicultora nacional e o servi\u00e7o ecossist\u00eamico de poliniza\u00e7\u00e3o da Mata Atl\u00e2ntica. Sua miss\u00e3o \u00e9 valorizar a exist\u00eancia de abelhas e das florestas e multiplicar as condi\u00e7\u00f5es necess\u00e1rias para a sustentabilidade desta rela\u00e7\u00e3o.<\/p><p>\u00a0<\/p><p>Por meio de a\u00e7\u00f5es integradas, o projeto Verde Mel atua em territ\u00f3rios estrat\u00e9gicos, estimulando cadeias produtivas e trazendo reconhecimento ao mel, como produto biol\u00f3gico e gastron\u00f4mico do Brasil. O projeto conta hoje com um melipon\u00e1rio central em Brotas (SP), que trabalha com: multiplica\u00e7\u00e3o de col\u00f4nias, amplia\u00e7\u00e3o do plantel de forma cont\u00ednua; capacita\u00e7\u00e3o de produtores e profissionais envolvidos em toda a cadeia; produ\u00e7\u00e3o de mel e subprodutos; distribui\u00e7\u00e3o de col\u00f4nias ap\u00f3s a multiplica\u00e7\u00e3o para produtores estrat\u00e9gicos na restaura\u00e7\u00e3o ecol\u00f3gica e na capacidade produtiva.<\/p><p>\u00a0<\/p><p>A partir da distribui\u00e7\u00e3o de col\u00f4nias, permite-se uma poliniza\u00e7\u00e3o estrat\u00e9gica do processo de restaura\u00e7\u00e3o, bem como o desenvolvimento da economia local e da agricultura familiar que, por meio do mel e outros subprodutos, poder\u00e3o ampliar a renda de forma sustent\u00e1vel.<\/p><p>\u00a0<\/p><p>O projeto possui uma rede de parceiros que contempla empresas privadas, organiza\u00e7\u00f5es da sociedade civil e institui\u00e7\u00f5es de ensino com vi\u00e9s p\u00fablico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6e164f elementor-widget elementor-widget-heading\" data-id=\"c6e164f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Resultados e Objetivos<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc2a050 elementor-widget elementor-widget-text-editor\" data-id=\"dc2a050\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O objetivo \u00e9 que, ap\u00f3s 10 anos do projeto, a contribui\u00e7\u00e3o no processo de recupera\u00e7\u00e3o ecol\u00f3gica atinja mais de 120.000 hectares de floresta nativa beneficiados com o servi\u00e7o de poliniza\u00e7\u00e3o.<\/p><p>\u00a0<\/p><p>Abaixo, os impactos do projeto at\u00e9 o momento:<\/p><p>\u2022 Formaliza\u00e7\u00e3o e fortalecimento estruturado da atividade a partir da cria\u00e7\u00e3o de um melipon\u00e1rio em Brotas (SP),;<br \/>\u2022 Suporte na conserva\u00e7\u00e3o direta da biodiversidade da fauna, com as abelhas nativas e, indireta por meio do fortalecimento da restaura\u00e7\u00e3o ecol\u00f3gica e do habitat para outras esp\u00e9cies. <br \/>\u2022 Atualmente temos mais de 200 col\u00f4nias de abelhas em multiplica\u00e7\u00e3o, crescimento do plantel em mais de 300%.<br \/>\u2022 Capacita\u00e7\u00e3o de mais de 30 atores-chave para dissemina\u00e7\u00e3o e amplia\u00e7\u00e3o do trabalho, entre eles est\u00e3o produtores, ONGs, profissionais e outros atores locais e multiplicadores.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<aside class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1fe6d80\" data-id=\"1fe6d80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-45b9b70 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45b9b70\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9a43058 project-side-item project-sectors\" data-id=\"9a43058\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0f6247 elementor-widget elementor-widget-heading\" data-id=\"e0f6247\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">regi\u00e3o<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9f341a elementor-widget elementor-widget-heading\" data-id=\"a9f341a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Sudeste<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ebf8914 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ebf8914\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b180d9e project-side-item project-investments\" data-id=\"b180d9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ddfea2 elementor-widget elementor-widget-heading\" data-id=\"4ddfea2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">n\u00fameros<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6adaa3 elementor-widget elementor-widget-premium-counter\" data-id=\"e6adaa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"premium-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"premium-counter premium-counter-area top\" data-duration=\"3000\" data-from-value=\"0\" data-to-value=\"120\" data-delimiter=\".\" data-rounding=\"0\">\n\t\t\t\n\t\t<div class=\"premium-counter-icon\">\n\n\t\t\t<span class=\"icon\" data-animation=\"\">\n\n\t\t\t\t\t\t\t\t\t<i class=\"premium-svg-nodraw premium-drawable-icon fas fa-tree\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\n\t\t\t<\/span>\n\t\t<\/div>\n\n\t\t\n\t\t<div class=\"premium-init-wrapper column\">\n\n\t\t\t<div class=\"premium-counter-value-wrap\">\n\t\t\t\t\n\t\t\t\t<span class=\"premium-counter-init\" id=\"counter-e6adaa3\">0<\/span>\n\n\t\t\t\t\t\t\t\t\t<span id=\"suffix\" class=\"counter-su-pre\">mil ha<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-counter-title\">\n\t\t\t\t\t<p class=\"premium-counter-title-val\">\n\t\t\t\t\t\t de \u00e1reas degradadas resturadas\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"premium-counter-desc\"> como meta, at\u00e9 2030<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aa09ee0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa09ee0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-53bf903 project-side-item project-sectors\" data-id=\"53bf903\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12a6c5d elementor-widget elementor-widget-heading\" data-id=\"12a6c5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">setor<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0698408 elementor-widget elementor-widget-heading\" data-id=\"0698408\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ind\u00fastria<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2261646 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2261646\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bc05213 project-side-item project-categories\" data-id=\"bc05213\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3b5c2f elementor-widget elementor-widget-heading\" data-id=\"e3b5c2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">CATEGORIA<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1aaa1d project-categories-list elementor-widget elementor-widget-text-editor\" data-id=\"b1aaa1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Preserva\u00e7\u00e3o, Restaura\u00e7\u00e3o e Bioeconomia<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/aside>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f9ebc0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f9ebc0b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1b651c\" data-id=\"f1b651c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff332be elementor-widget elementor-widget-heading\" data-id=\"ff332be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mais Projetos da SYLVAMO DO BRASIL\u200b<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2114445 elementor-widget__width-inherit custom-widget-projects premium-blog-align-left elementor-widget elementor-widget-premium-addon-blog\" data-id=\"2114445\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;premium_blog_columns_number&quot;:&quot;33.33%&quot;,&quot;premium_blog_grid&quot;:&quot;yes&quot;,&quot;premium_blog_layout&quot;:&quot;even&quot;,&quot;premium_blog_columns_number_tablet&quot;:&quot;50%&quot;,&quot;premium_blog_columns_number_mobile&quot;:&quot;100%&quot;,&quot;scroll_to_offset&quot;:&quot;yes&quot;}\" data-widget_type=\"premium-addon-blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\n\n\t\t\t\t<div class=\"premium-blog-wrap  premium-blog-even\" data-page=\"5525\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"1\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-banner\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumb-effect-wrapper\">\n\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-container premium-blog-bright-effect\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg\" class=\"attachment-medium size-medium wp-image-3540\" alt=\"terra\" srcset=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg 300w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-overlay\">\n\t\t\t\t\t\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/parque-florestal-sao-marcelo\/\" target=\"_self\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper \">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-cats-container\">\n\t\t\t\t\t\t\t\t<ul class=\"post-categories\">\n\t\t\t\t\t\t\t\t\t<li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/ano\/2022\/\" class=\"elementor-repeater-item-5e163ac\">2022<\/a><\/li><li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/setor\/industria\/\" class=\"\">Ind\u00fastria<\/a><\/li><li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/categoria\/preservacao_restauracao_bioeconomia\/\" class=\"\">Preserva\u00e7\u00e3o, Restaura\u00e7\u00e3o e Bioeconomia<\/a><\/li><li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/alfabeto\/s\/\" class=\"\">S<\/a><\/li><li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/regiao\/sudeste\/\" class=\"\">Sudeste<\/a><\/li>\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/parque-florestal-sao-marcelo\/\" target=\"_self\">\n\t\t\t\tParque florestal S\u00e3o Marcelo\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Sylvamo do Brasil<\/p>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"1\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-banner\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumb-effect-wrapper\">\n\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-container premium-blog-bright-effect\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg\" class=\"attachment-medium size-medium wp-image-3540\" alt=\"terra\" srcset=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg 300w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-overlay\">\n\t\t\t\t\t\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/projeto-verde-mel\/\" target=\"_self\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper \">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-cats-container\">\n\t\t\t\t\t\t\t\t<ul class=\"post-categories\">\n\t\t\t\t\t\t\t\t\t<li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/ano\/2022\/\" class=\"elementor-repeater-item-5e163ac\">2022<\/a><\/li><li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/setor\/industria\/\" class=\"\">Ind\u00fastria<\/a><\/li><li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/categoria\/preservacao_restauracao_bioeconomia\/\" class=\"\">Preserva\u00e7\u00e3o, Restaura\u00e7\u00e3o e Bioeconomia<\/a><\/li><li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/alfabeto\/s\/\" class=\"\">S<\/a><\/li><li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/regiao\/sudeste\/\" class=\"\">Sudeste<\/a><\/li>\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/projeto-verde-mel\/\" target=\"_self\">\n\t\t\t\tProjeto Verde Mel\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Sylvamo do Brasil<\/p>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"1\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-banner\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumb-effect-wrapper\">\n\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-container premium-blog-bright-effect\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg\" class=\"attachment-medium size-medium wp-image-3540\" alt=\"terra\" srcset=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg 300w, https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-overlay\">\n\t\t\t\t\t\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/programa-raizes-do-mogi-guacu\/\" target=\"_self\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper \">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-cats-container\">\n\t\t\t\t\t\t\t\t<ul class=\"post-categories\">\n\t\t\t\t\t\t\t\t\t<li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/ano\/2022\/\" class=\"elementor-repeater-item-5e163ac\">2022<\/a><\/li><li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/setor\/industria\/\" class=\"\">Ind\u00fastria<\/a><\/li><li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/categoria\/preservacao_restauracao_bioeconomia\/\" class=\"\">Preserva\u00e7\u00e3o, Restaura\u00e7\u00e3o e Bioeconomia<\/a><\/li><li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/alfabeto\/s\/\" class=\"\">S<\/a><\/li><li><a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/category\/regiao\/sudeste\/\" class=\"\">Sudeste<\/a><\/li>\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/programa-raizes-do-mogi-guacu\/\" target=\"_self\">\n\t\t\t\tPrograma Ra\u00edzes do Mogi Gua\u00e7u\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"premium-blog-content-inner-wrapper\">\n\t\t<p class=\"premium-blog-post-content\">Sylvamo do Brasil<\/p>\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sylvamo do Brasil<\/p>","protected":false},"author":5,"featured_media":3540,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[161,44,11,76,54],"tags":[164,157],"class_list":["post-5525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-161","category-industria","category-preservacao_restauracao_bioeconomia","category-s","category-sudeste","tag-164","tag-sylvamo-do-brasil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projeto Verde Mel - Brasil Pelo Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brasilpelomeioambiente.com.br\/en\/honey-green-project\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projeto Verde Mel - Brasil Pelo Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Sylvamo do Brasil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brasilpelomeioambiente.com.br\/en\/honey-green-project\/\" \/>\n<meta property=\"og:site_name\" content=\"Brasil Pelo Meio Ambiente\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amchambrasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-10T10:01:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-11T17:31:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kaike Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amchambr\" \/>\n<meta name=\"twitter:site\" content=\"@amchambr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kaike Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/projeto-verde-mel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/projeto-verde-mel\\\/\"},\"author\":{\"name\":\"Kaike Silveira\",\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#\\\/schema\\\/person\\\/9d0a98e02ce7aaaad190174d8c02d8ff\"},\"headline\":\"Projeto Verde Mel\",\"datePublished\":\"2022-11-10T10:01:02+00:00\",\"dateModified\":\"2023-10-11T17:31:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/projeto-verde-mel\\\/\"},\"wordCount\":523,\"publisher\":{\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/projeto-verde-mel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg\",\"keywords\":[\"2022\",\"Sylvamo do Brasil\"],\"articleSection\":[\"2022\",\"Ind\u00fastria\",\"Preserva\u00e7\u00e3o, Restaura\u00e7\u00e3o e Bioeconomia\",\"S\",\"Sudeste\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/projeto-verde-mel\\\/\",\"url\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/projeto-verde-mel\\\/\",\"name\":\"Projeto Verde Mel - Brasil Pelo Meio Ambiente\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/projeto-verde-mel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/projeto-verde-mel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg\",\"datePublished\":\"2022-11-10T10:01:02+00:00\",\"dateModified\":\"2023-10-11T17:31:41+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/projeto-verde-mel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/projeto-verde-mel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg\",\"contentUrl\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg\",\"width\":300,\"height\":300,\"caption\":\"Sustainable living environmentalist hand holding green earth\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#website\",\"url\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/\",\"name\":\"Brasil Pelo Meio Ambiente\",\"description\":\"O projeto Brasil Pelo Meio Ambiente surgiu da necessidade de compartilhar as melhores pr\u00e1ticas empresariais brasileiras sobre os temas de preserva\u00e7\u00e3o ambiental e sustentabilidade\",\"publisher\":{\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#organization\"},\"alternateName\":\"BPMA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#organization\",\"name\":\"Brasil Pelo Meio Ambiente\",\"url\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/BpMA-Amcham-ICC_logotipos.png\",\"contentUrl\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/BpMA-Amcham-ICC_logotipos.png\",\"width\":1920,\"height\":1080,\"caption\":\"Brasil Pelo Meio Ambiente\"},\"image\":{\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amchambrasil\",\"https:\\\/\\\/x.com\\\/amchambr\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/brasilpelomeioambiente.com.br\\\/#\\\/schema\\\/person\\\/9d0a98e02ce7aaaad190174d8c02d8ff\",\"name\":\"Kaike Silveira\",\"url\":\"https:\\\/\\\/brasilpelomeioambiente.com.br\\\/en\\\/author\\\/kaike-silveira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Green Honey Project - Brazil for the Environment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brasilpelomeioambiente.com.br\/en\/honey-green-project\/","og_locale":"en_US","og_type":"article","og_title":"Projeto Verde Mel - Brasil Pelo Meio Ambiente","og_description":"Sylvamo do Brasil","og_url":"https:\/\/brasilpelomeioambiente.com.br\/en\/honey-green-project\/","og_site_name":"Brasil Pelo Meio Ambiente","article_publisher":"https:\/\/www.facebook.com\/amchambrasil","article_published_time":"2022-11-10T10:01:02+00:00","article_modified_time":"2023-10-11T17:31:41+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg","type":"image\/jpeg"}],"author":"Kaike Silveira","twitter_card":"summary_large_image","twitter_creator":"@amchambr","twitter_site":"@amchambr","twitter_misc":{"Written by":"Kaike Silveira","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/brasilpelomeioambiente.com.br\/projeto-verde-mel\/#article","isPartOf":{"@id":"https:\/\/brasilpelomeioambiente.com.br\/projeto-verde-mel\/"},"author":{"name":"Kaike Silveira","@id":"http:\/\/brasilpelomeioambiente.com.br\/#\/schema\/person\/9d0a98e02ce7aaaad190174d8c02d8ff"},"headline":"Projeto Verde Mel","datePublished":"2022-11-10T10:01:02+00:00","dateModified":"2023-10-11T17:31:41+00:00","mainEntityOfPage":{"@id":"https:\/\/brasilpelomeioambiente.com.br\/projeto-verde-mel\/"},"wordCount":523,"publisher":{"@id":"http:\/\/brasilpelomeioambiente.com.br\/#organization"},"image":{"@id":"https:\/\/brasilpelomeioambiente.com.br\/projeto-verde-mel\/#primaryimage"},"thumbnailUrl":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg","keywords":["2022","Sylvamo do Brasil"],"articleSection":["2022","Ind\u00fastria","Preserva\u00e7\u00e3o, Restaura\u00e7\u00e3o e Bioeconomia","S","Sudeste"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/brasilpelomeioambiente.com.br\/projeto-verde-mel\/","url":"https:\/\/brasilpelomeioambiente.com.br\/projeto-verde-mel\/","name":"Green Honey Project - Brazil for the Environment","isPartOf":{"@id":"http:\/\/brasilpelomeioambiente.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brasilpelomeioambiente.com.br\/projeto-verde-mel\/#primaryimage"},"image":{"@id":"https:\/\/brasilpelomeioambiente.com.br\/projeto-verde-mel\/#primaryimage"},"thumbnailUrl":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg","datePublished":"2022-11-10T10:01:02+00:00","dateModified":"2023-10-11T17:31:41+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brasilpelomeioambiente.com.br\/projeto-verde-mel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/brasilpelomeioambiente.com.br\/projeto-verde-mel\/#primaryimage","url":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg","contentUrl":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/10\/sustainable-living-environmentalist-hand-holding-green-earth300x300-2.jpg","width":300,"height":300,"caption":"Sustainable living environmentalist hand holding green earth"},{"@type":"WebSite","@id":"http:\/\/brasilpelomeioambiente.com.br\/#website","url":"http:\/\/brasilpelomeioambiente.com.br\/","name":"Brazil for the Environment","description":"The Brazil for the Environment project arose from the need to share Brazil's best business practices on the issues of environmental preservation and sustainability","publisher":{"@id":"http:\/\/brasilpelomeioambiente.com.br\/#organization"},"alternateName":"BPMA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/brasilpelomeioambiente.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/brasilpelomeioambiente.com.br\/#organization","name":"Brazil for the Environment","url":"http:\/\/brasilpelomeioambiente.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/brasilpelomeioambiente.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos.png","contentUrl":"https:\/\/brasilpelomeioambiente.com.br\/wp-content\/uploads\/2022\/08\/BpMA-Amcham-ICC_logotipos.png","width":1920,"height":1080,"caption":"Brasil Pelo Meio Ambiente"},"image":{"@id":"http:\/\/brasilpelomeioambiente.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amchambrasil","https:\/\/x.com\/amchambr"]},{"@type":"Person","@id":"http:\/\/brasilpelomeioambiente.com.br\/#\/schema\/person\/9d0a98e02ce7aaaad190174d8c02d8ff","name":"Kaike Silveira","url":"https:\/\/brasilpelomeioambiente.com.br\/en\/author\/kaike-silveira\/"}]}},"_links":{"self":[{"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/posts\/5525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/comments?post=5525"}],"version-history":[{"count":0,"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/posts\/5525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/media\/3540"}],"wp:attachment":[{"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/media?parent=5525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/categories?post=5525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brasilpelomeioambiente.com.br\/en\/wp-json\/wp\/v2\/tags?post=5525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}